{"id":3554,"date":"2011-01-05T15:25:27","date_gmt":"2011-01-05T15:25:27","guid":{"rendered":"https:\/\/test.transversalmedia.eu\/randomberlinchick-einsturzende-neubauten\/"},"modified":"2011-01-05T15:25:27","modified_gmt":"2011-01-05T15:25:27","slug":"randomberlinchick-einsturzende-neubauten","status":"publish","type":"post","link":"https:\/\/theresearchpapers.org\/archive\/randomberlinchick-einsturzende-neubauten\/","title":{"rendered":""},"content":{"rendered":"<p>http:\/\/www.youtube.com\/watch?v=pm_aut6RDAY<\/p>\n<p><a href=\"http:\/\/randomberlinchick.tumblr.com\/post\/2609635930\/einsturzende-neubauten-stella-maris-via\">randomberlinchick<\/a>:<\/p>\n<blockquote>\n<p><a href=\"http:\/\/www.youtube.com\/watch?v=pm_aut6RDAY\">Einst\u00fcrzende Neubauten &#8211; Stella Maris<\/a> (via <a href=\"http:\/\/youtube.com\/user\/MariaAntonia\">MariaAntonia<\/a>)<\/p>\n<p>@ RLP!<\/p>\n<\/blockquote>\n<p>HA! This is the one I was going to post for you!<\/p>\n<p>I love how Blixa Bargeld looks his usual creepy (as in, horror movie creepy) self in this video. That aesthetic is the reason I fell in love with the band in the first place.<\/p>\n<p>Also: a band whose albums (at least the originals from the &lsquo;80&rsquo;s and early &#8217;90&rsquo;s) are extremely difficult to find: Die Haut. Bargeld was part of that ensemble that also counted Lydia Lunch amongst its ranks.<\/p>\n<div class=\"attribution\">(<span>Source:<\/span> <a href=\"http:\/\/www.youtube.com\/\">http:\/\/www.youtube.com\/<\/a>)<\/div>\n","protected":false},"excerpt":{"rendered":"<p>http:\/\/www.youtube.com\/watch?v=pm_aut6RDAY randomberlinchick: Einst\u00fcrzende Neubauten &#8211; Stella Maris (via MariaAntonia) @ RLP! HA! This is the one I was going to post for you! I love how Blixa Bargeld looks his usual creepy (as in, horror movie creepy) self in this video. That aesthetic is the reason I fell in love with the band in the &#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"video","meta":{"loftocean_post_format_gallery":"","loftocean_post_format_gallery_ids":"","loftocean_post_format_gallery_urls":"","loftocean_post_format_video_id":0,"loftocean_post_format_video_url":"","loftocean_post_format_video_type":"","loftocean_post_format_video":"","loftocean_post_format_audio_type":"","loftocean_post_format_audio_url":"","loftocean_post_format_audio_id":0,"loftocean_post_format_audio":"","loftocean-featured-post":"","loftocean-like-count":0,"loftocean-view-count":1103,"loftocean_coauthors":"","alpaca_post_content_reading_setting":"","alpaca_reading_speed_per_minute":0,"alpaca_reading_speed_unit":"","alpaca_single_post_template_layout":"","footnotes":""},"categories":[1],"tags":[311,1437,1489],"class_list":["post-3554","post","type-post","status-publish","format-video","hentry","category-uncategorized","tag-blixa-bargeld","tag-music-i-love","tag-neubauten","post_format-post-format-video"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>- The Research Papers<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/theresearchpapers.org\/archive\/randomberlinchick-einsturzende-neubauten\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"- The Research Papers\" \/>\n<meta property=\"og:description\" content=\"http:\/\/www.youtube.com\/watch?v=pm_aut6RDAY randomberlinchick: Einst\u00fcrzende Neubauten &#8211; Stella Maris (via MariaAntonia) @ RLP! HA! This is the one I was going to post for you! I love how Blixa Bargeld looks his usual creepy (as in, horror movie creepy) self in this video. That aesthetic is the reason I fell in love with the band in the ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/theresearchpapers.org\/archive\/randomberlinchick-einsturzende-neubauten\/\" \/>\n<meta property=\"og:site_name\" content=\"The Research Papers\" \/>\n<meta property=\"article:published_time\" content=\"2011-01-05T15:25:27+00:00\" \/>\n<meta name=\"author\" content=\"Flavia Dzodan\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Flavia Dzodan\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/theresearchpapers.org\/archive\/randomberlinchick-einsturzende-neubauten\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/theresearchpapers.org\/archive\/randomberlinchick-einsturzende-neubauten\/\"},\"author\":{\"name\":\"Flavia Dzodan\",\"@id\":\"https:\/\/theresearchpapers.org\/archive\/#\/schema\/person\/69281d20ffc4c45de29cedfa61ec6e38\"},\"headline\":\"No title\",\"datePublished\":\"2011-01-05T15:25:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/theresearchpapers.org\/archive\/randomberlinchick-einsturzende-neubauten\/\"},\"wordCount\":109,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/theresearchpapers.org\/archive\/#organization\"},\"keywords\":[\"Blixa Bargeld\",\"music I love\",\"Neubauten\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/theresearchpapers.org\/archive\/randomberlinchick-einsturzende-neubauten\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/theresearchpapers.org\/archive\/randomberlinchick-einsturzende-neubauten\/\",\"url\":\"https:\/\/theresearchpapers.org\/archive\/randomberlinchick-einsturzende-neubauten\/\",\"name\":\"- The Research Papers\",\"isPartOf\":{\"@id\":\"https:\/\/theresearchpapers.org\/archive\/#website\"},\"datePublished\":\"2011-01-05T15:25:27+00:00\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/theresearchpapers.org\/archive\/randomberlinchick-einsturzende-neubauten\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/theresearchpapers.org\/archive\/#website\",\"url\":\"https:\/\/theresearchpapers.org\/archive\/\",\"name\":\"The Research Papers\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/theresearchpapers.org\/archive\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/theresearchpapers.org\/archive\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/theresearchpapers.org\/archive\/#organization\",\"name\":\"The Research Papers\",\"url\":\"https:\/\/theresearchpapers.org\/archive\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/theresearchpapers.org\/archive\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/theresearchpapers.org\/archive\/wp-content\/uploads\/2021\/07\/cropped-Screenshot-2021-07-29-at-15.01.52.png\",\"contentUrl\":\"https:\/\/theresearchpapers.org\/archive\/wp-content\/uploads\/2021\/07\/cropped-Screenshot-2021-07-29-at-15.01.52.png\",\"width\":943,\"height\":269,\"caption\":\"The Research Papers\"},\"image\":{\"@id\":\"https:\/\/theresearchpapers.org\/archive\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/theresearchpapers.org\/archive\/#\/schema\/person\/69281d20ffc4c45de29cedfa61ec6e38\",\"name\":\"Flavia Dzodan\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/theresearchpapers.org\/archive\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a3eedf3ed7334274cfc4d525a46aa4e85c5a246418835528410ecf354d0861e1?s=96&d=monsterid&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a3eedf3ed7334274cfc4d525a46aa4e85c5a246418835528410ecf354d0861e1?s=96&d=monsterid&r=g\",\"caption\":\"Flavia Dzodan\"},\"url\":\"https:\/\/theresearchpapers.org\/archive\/author\/trp-adm-fdz02\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"- The Research Papers","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/theresearchpapers.org\/archive\/randomberlinchick-einsturzende-neubauten\/","og_locale":"en_US","og_type":"article","og_title":"- The Research Papers","og_description":"http:\/\/www.youtube.com\/watch?v=pm_aut6RDAY randomberlinchick: Einst\u00fcrzende Neubauten &#8211; Stella Maris (via MariaAntonia) @ RLP! HA! This is the one I was going to post for you! I love how Blixa Bargeld looks his usual creepy (as in, horror movie creepy) self in this video. That aesthetic is the reason I fell in love with the band in the ...","og_url":"https:\/\/theresearchpapers.org\/archive\/randomberlinchick-einsturzende-neubauten\/","og_site_name":"The Research Papers","article_published_time":"2011-01-05T15:25:27+00:00","author":"Flavia Dzodan","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Flavia Dzodan","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/theresearchpapers.org\/archive\/randomberlinchick-einsturzende-neubauten\/#article","isPartOf":{"@id":"https:\/\/theresearchpapers.org\/archive\/randomberlinchick-einsturzende-neubauten\/"},"author":{"name":"Flavia Dzodan","@id":"https:\/\/theresearchpapers.org\/archive\/#\/schema\/person\/69281d20ffc4c45de29cedfa61ec6e38"},"headline":"No title","datePublished":"2011-01-05T15:25:27+00:00","mainEntityOfPage":{"@id":"https:\/\/theresearchpapers.org\/archive\/randomberlinchick-einsturzende-neubauten\/"},"wordCount":109,"commentCount":0,"publisher":{"@id":"https:\/\/theresearchpapers.org\/archive\/#organization"},"keywords":["Blixa Bargeld","music I love","Neubauten"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/theresearchpapers.org\/archive\/randomberlinchick-einsturzende-neubauten\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/theresearchpapers.org\/archive\/randomberlinchick-einsturzende-neubauten\/","url":"https:\/\/theresearchpapers.org\/archive\/randomberlinchick-einsturzende-neubauten\/","name":"- The Research Papers","isPartOf":{"@id":"https:\/\/theresearchpapers.org\/archive\/#website"},"datePublished":"2011-01-05T15:25:27+00:00","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/theresearchpapers.org\/archive\/randomberlinchick-einsturzende-neubauten\/"]}]},{"@type":"WebSite","@id":"https:\/\/theresearchpapers.org\/archive\/#website","url":"https:\/\/theresearchpapers.org\/archive\/","name":"The Research Papers","description":"","publisher":{"@id":"https:\/\/theresearchpapers.org\/archive\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/theresearchpapers.org\/archive\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/theresearchpapers.org\/archive\/#organization","name":"The Research Papers","url":"https:\/\/theresearchpapers.org\/archive\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/theresearchpapers.org\/archive\/#\/schema\/logo\/image\/","url":"https:\/\/theresearchpapers.org\/archive\/wp-content\/uploads\/2021\/07\/cropped-Screenshot-2021-07-29-at-15.01.52.png","contentUrl":"https:\/\/theresearchpapers.org\/archive\/wp-content\/uploads\/2021\/07\/cropped-Screenshot-2021-07-29-at-15.01.52.png","width":943,"height":269,"caption":"The Research Papers"},"image":{"@id":"https:\/\/theresearchpapers.org\/archive\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/theresearchpapers.org\/archive\/#\/schema\/person\/69281d20ffc4c45de29cedfa61ec6e38","name":"Flavia Dzodan","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/theresearchpapers.org\/archive\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a3eedf3ed7334274cfc4d525a46aa4e85c5a246418835528410ecf354d0861e1?s=96&d=monsterid&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a3eedf3ed7334274cfc4d525a46aa4e85c5a246418835528410ecf354d0861e1?s=96&d=monsterid&r=g","caption":"Flavia Dzodan"},"url":"https:\/\/theresearchpapers.org\/archive\/author\/trp-adm-fdz02\/"}]}},"loftoceanMetas":{"readingTime":"&lt; 1 min read","authorName":"Flavia Dzodan","categories":[{"name":"Uncategorized","link":"https:\/\/theresearchpapers.org\/archive\/category\/uncategorized\/","count":3467}],"date":"05.01.2011"},"_links":{"self":[{"href":"https:\/\/theresearchpapers.org\/archive\/wp-json\/wp\/v2\/posts\/3554","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/theresearchpapers.org\/archive\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/theresearchpapers.org\/archive\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/theresearchpapers.org\/archive\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/theresearchpapers.org\/archive\/wp-json\/wp\/v2\/comments?post=3554"}],"version-history":[{"count":0,"href":"https:\/\/theresearchpapers.org\/archive\/wp-json\/wp\/v2\/posts\/3554\/revisions"}],"wp:attachment":[{"href":"https:\/\/theresearchpapers.org\/archive\/wp-json\/wp\/v2\/media?parent=3554"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/theresearchpapers.org\/archive\/wp-json\/wp\/v2\/categories?post=3554"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/theresearchpapers.org\/archive\/wp-json\/wp\/v2\/tags?post=3554"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}