{"id":4415,"date":"2010-10-14T18:46:10","date_gmt":"2010-10-14T18:46:10","guid":{"rendered":"https:\/\/test.transversalmedia.eu\/vintage-fitness-equipment-what-no-yoga-pants\/"},"modified":"2010-10-14T18:46:10","modified_gmt":"2010-10-14T18:46:10","slug":"vintage-fitness-equipment-what-no-yoga-pants","status":"publish","type":"post","link":"https:\/\/theresearchpapers.org\/archive\/vintage-fitness-equipment-what-no-yoga-pants\/","title":{"rendered":""},"content":{"rendered":"<div id='gallery-1' class='gallery galleryid-4415 gallery-columns-3 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/theresearchpapers.org\/archive\/vintage-fitness-equipment-what-no-yoga-pants\/attachment\/4416\/'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/theresearchpapers.org\/archive\/wp-content\/uploads\/2010\/10\/tumblr_laamsyPpBp1qbkli6o1_500-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/theresearchpapers.org\/archive\/wp-content\/uploads\/2010\/10\/tumblr_laamsyPpBp1qbkli6o1_500-150x150.jpg 150w, https:\/\/theresearchpapers.org\/archive\/wp-content\/uploads\/2010\/10\/tumblr_laamsyPpBp1qbkli6o1_500-300x300.jpg 300w\" sizes=\"255px\" data-loftocean-lazy-load-sizes=\"(max-width: 150px) 100vw, 150px\" data-loftocean-loading-image=\"on\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<p><a href=\"http:\/\/lumq.com\/07\/vintage-fitness-equipment\/\"><strong>Vintage Fitness Equipment<\/strong><\/a><\/p>\n<p>What? No yoga pants?!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vintage Fitness Equipment What? No yoga pants?!<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"gallery","meta":{"loftocean_post_format_gallery":"","loftocean_post_format_gallery_ids":"","loftocean_post_format_gallery_urls":"","loftocean_post_format_video_id":0,"loftocean_post_format_video_url":"","loftocean_post_format_video_type":"","loftocean_post_format_video":"","loftocean_post_format_audio_type":"","loftocean_post_format_audio_url":"","loftocean_post_format_audio_id":0,"loftocean_post_format_audio":"","loftocean-featured-post":"","loftocean-like-count":0,"loftocean-view-count":1212,"loftocean_coauthors":"","alpaca_post_content_reading_setting":"","alpaca_reading_speed_per_minute":0,"alpaca_reading_speed_unit":"","alpaca_single_post_template_layout":"","footnotes":""},"categories":[1],"tags":[782,29,2326],"class_list":["post-4415","post","type-post","status-publish","format-gallery","hentry","category-uncategorized","tag-fitness","tag-vintage","tag-xs","post_format-post-format-gallery"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>- The Research Papers<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/theresearchpapers.org\/archive\/vintage-fitness-equipment-what-no-yoga-pants\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"- The Research Papers\" \/>\n<meta property=\"og:description\" content=\"Vintage Fitness Equipment What? No yoga pants?!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/theresearchpapers.org\/archive\/vintage-fitness-equipment-what-no-yoga-pants\/\" \/>\n<meta property=\"og:site_name\" content=\"The Research Papers\" \/>\n<meta property=\"article:published_time\" content=\"2010-10-14T18:46:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/theresearchpapers.org\/archive\/wp-content\/uploads\/2010\/10\/tumblr_laamsyPpBp1qbkli6o1_500-150x150.jpg\" \/>\n<meta name=\"author\" content=\"Flavia Dzodan\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Flavia Dzodan\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/theresearchpapers.org\/archive\/vintage-fitness-equipment-what-no-yoga-pants\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/theresearchpapers.org\/archive\/vintage-fitness-equipment-what-no-yoga-pants\/\"},\"author\":{\"name\":\"Flavia Dzodan\",\"@id\":\"https:\/\/theresearchpapers.org\/archive\/#\/schema\/person\/69281d20ffc4c45de29cedfa61ec6e38\"},\"headline\":\"No title\",\"datePublished\":\"2010-10-14T18:46:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/theresearchpapers.org\/archive\/vintage-fitness-equipment-what-no-yoga-pants\/\"},\"wordCount\":8,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/theresearchpapers.org\/archive\/#organization\"},\"keywords\":[\"fitness\",\"vintage\",\"xs\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/theresearchpapers.org\/archive\/vintage-fitness-equipment-what-no-yoga-pants\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/theresearchpapers.org\/archive\/vintage-fitness-equipment-what-no-yoga-pants\/\",\"url\":\"https:\/\/theresearchpapers.org\/archive\/vintage-fitness-equipment-what-no-yoga-pants\/\",\"name\":\"- The Research Papers\",\"isPartOf\":{\"@id\":\"https:\/\/theresearchpapers.org\/archive\/#website\"},\"datePublished\":\"2010-10-14T18:46:10+00:00\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/theresearchpapers.org\/archive\/vintage-fitness-equipment-what-no-yoga-pants\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/theresearchpapers.org\/archive\/#website\",\"url\":\"https:\/\/theresearchpapers.org\/archive\/\",\"name\":\"The Research Papers\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/theresearchpapers.org\/archive\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/theresearchpapers.org\/archive\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/theresearchpapers.org\/archive\/#organization\",\"name\":\"The Research Papers\",\"url\":\"https:\/\/theresearchpapers.org\/archive\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/theresearchpapers.org\/archive\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/theresearchpapers.org\/archive\/wp-content\/uploads\/2021\/07\/cropped-Screenshot-2021-07-29-at-15.01.52.png\",\"contentUrl\":\"https:\/\/theresearchpapers.org\/archive\/wp-content\/uploads\/2021\/07\/cropped-Screenshot-2021-07-29-at-15.01.52.png\",\"width\":943,\"height\":269,\"caption\":\"The Research Papers\"},\"image\":{\"@id\":\"https:\/\/theresearchpapers.org\/archive\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/theresearchpapers.org\/archive\/#\/schema\/person\/69281d20ffc4c45de29cedfa61ec6e38\",\"name\":\"Flavia Dzodan\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/theresearchpapers.org\/archive\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a3eedf3ed7334274cfc4d525a46aa4e85c5a246418835528410ecf354d0861e1?s=96&d=monsterid&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a3eedf3ed7334274cfc4d525a46aa4e85c5a246418835528410ecf354d0861e1?s=96&d=monsterid&r=g\",\"caption\":\"Flavia Dzodan\"},\"url\":\"https:\/\/theresearchpapers.org\/archive\/author\/trp-adm-fdz02\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"- The Research Papers","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/theresearchpapers.org\/archive\/vintage-fitness-equipment-what-no-yoga-pants\/","og_locale":"en_US","og_type":"article","og_title":"- The Research Papers","og_description":"Vintage Fitness Equipment What? No yoga pants?!","og_url":"https:\/\/theresearchpapers.org\/archive\/vintage-fitness-equipment-what-no-yoga-pants\/","og_site_name":"The Research Papers","article_published_time":"2010-10-14T18:46:10+00:00","og_image":[{"url":"https:\/\/theresearchpapers.org\/archive\/wp-content\/uploads\/2010\/10\/tumblr_laamsyPpBp1qbkli6o1_500-150x150.jpg","type":"","width":"","height":""}],"author":"Flavia Dzodan","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Flavia Dzodan"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/theresearchpapers.org\/archive\/vintage-fitness-equipment-what-no-yoga-pants\/#article","isPartOf":{"@id":"https:\/\/theresearchpapers.org\/archive\/vintage-fitness-equipment-what-no-yoga-pants\/"},"author":{"name":"Flavia Dzodan","@id":"https:\/\/theresearchpapers.org\/archive\/#\/schema\/person\/69281d20ffc4c45de29cedfa61ec6e38"},"headline":"No title","datePublished":"2010-10-14T18:46:10+00:00","mainEntityOfPage":{"@id":"https:\/\/theresearchpapers.org\/archive\/vintage-fitness-equipment-what-no-yoga-pants\/"},"wordCount":8,"commentCount":0,"publisher":{"@id":"https:\/\/theresearchpapers.org\/archive\/#organization"},"keywords":["fitness","vintage","xs"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/theresearchpapers.org\/archive\/vintage-fitness-equipment-what-no-yoga-pants\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/theresearchpapers.org\/archive\/vintage-fitness-equipment-what-no-yoga-pants\/","url":"https:\/\/theresearchpapers.org\/archive\/vintage-fitness-equipment-what-no-yoga-pants\/","name":"- The Research Papers","isPartOf":{"@id":"https:\/\/theresearchpapers.org\/archive\/#website"},"datePublished":"2010-10-14T18:46:10+00:00","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/theresearchpapers.org\/archive\/vintage-fitness-equipment-what-no-yoga-pants\/"]}]},{"@type":"WebSite","@id":"https:\/\/theresearchpapers.org\/archive\/#website","url":"https:\/\/theresearchpapers.org\/archive\/","name":"The Research Papers","description":"","publisher":{"@id":"https:\/\/theresearchpapers.org\/archive\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/theresearchpapers.org\/archive\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/theresearchpapers.org\/archive\/#organization","name":"The Research Papers","url":"https:\/\/theresearchpapers.org\/archive\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/theresearchpapers.org\/archive\/#\/schema\/logo\/image\/","url":"https:\/\/theresearchpapers.org\/archive\/wp-content\/uploads\/2021\/07\/cropped-Screenshot-2021-07-29-at-15.01.52.png","contentUrl":"https:\/\/theresearchpapers.org\/archive\/wp-content\/uploads\/2021\/07\/cropped-Screenshot-2021-07-29-at-15.01.52.png","width":943,"height":269,"caption":"The Research Papers"},"image":{"@id":"https:\/\/theresearchpapers.org\/archive\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/theresearchpapers.org\/archive\/#\/schema\/person\/69281d20ffc4c45de29cedfa61ec6e38","name":"Flavia Dzodan","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/theresearchpapers.org\/archive\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a3eedf3ed7334274cfc4d525a46aa4e85c5a246418835528410ecf354d0861e1?s=96&d=monsterid&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a3eedf3ed7334274cfc4d525a46aa4e85c5a246418835528410ecf354d0861e1?s=96&d=monsterid&r=g","caption":"Flavia Dzodan"},"url":"https:\/\/theresearchpapers.org\/archive\/author\/trp-adm-fdz02\/"}]}},"loftoceanMetas":{"readingTime":"&lt; 1 min read","authorName":"Flavia Dzodan","categories":[{"name":"Uncategorized","link":"https:\/\/theresearchpapers.org\/archive\/category\/uncategorized\/","count":3467}],"date":"14.10.2010"},"_links":{"self":[{"href":"https:\/\/theresearchpapers.org\/archive\/wp-json\/wp\/v2\/posts\/4415","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/theresearchpapers.org\/archive\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/theresearchpapers.org\/archive\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/theresearchpapers.org\/archive\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/theresearchpapers.org\/archive\/wp-json\/wp\/v2\/comments?post=4415"}],"version-history":[{"count":0,"href":"https:\/\/theresearchpapers.org\/archive\/wp-json\/wp\/v2\/posts\/4415\/revisions"}],"wp:attachment":[{"href":"https:\/\/theresearchpapers.org\/archive\/wp-json\/wp\/v2\/media?parent=4415"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/theresearchpapers.org\/archive\/wp-json\/wp\/v2\/categories?post=4415"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/theresearchpapers.org\/archive\/wp-json\/wp\/v2\/tags?post=4415"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}