{"id":484,"date":"2012-08-06T11:45:59","date_gmt":"2012-08-06T11:45:59","guid":{"rendered":"https:\/\/test.transversalmedia.eu\/the-world-outside-right-now-meanwhile\/"},"modified":"2012-08-06T11:45:59","modified_gmt":"2012-08-06T11:45:59","slug":"the-world-outside-right-now-meanwhile","status":"publish","type":"post","link":"https:\/\/theresearchpapers.org\/archive\/the-world-outside-right-now-meanwhile\/","title":{"rendered":""},"content":{"rendered":"<p>The world outside right now:<\/p>\n<p><figure class=\"tmblr-full\" data-orig-height=\"667\" data-orig-width=\"500\"><img decoding=\"async\" src=\"https:\/\/theresearchpapers.org\/archive\/wp-content\/uploads\/2021\/08\/40c3e7bda371eecea1f6acd0487c93a62e40f648.jpg\" data-orig-height=\"667\" data-orig-width=\"500\" \/><\/figure>\n<\/p>\n<p>Meanwhile, overlord Number 1 (who is actually &ldquo;overlady&rdquo;):<\/p>\n<p><figure class=\"tmblr-full\" data-orig-height=\"667\" data-orig-width=\"500\"><img decoding=\"async\" src=\"https:\/\/theresearchpapers.org\/archive\/wp-content\/uploads\/2021\/08\/608a47e8f5724e392b7ec2a5272348e352d8ebd2.jpg\" data-orig-height=\"667\" data-orig-width=\"500\" \/><\/figure>\n<\/p>\n<p>And overlord Number 2:<\/p>\n<p><figure class=\"tmblr-full\" data-orig-height=\"500\" data-orig-width=\"500\"><img decoding=\"async\" src=\"https:\/\/theresearchpapers.org\/archive\/wp-content\/uploads\/2021\/08\/f05d81f8781e5174da57a210e1d4cc9c2f852269.jpg\" data-orig-height=\"500\" data-orig-width=\"500\" \/><\/figure><\/p>\n","protected":false},"excerpt":{"rendered":"<p>The world outside right now: Meanwhile, overlord Number 1 (who is actually &ldquo;overlady&rdquo;): And overlord Number 2:<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"loftocean_post_format_gallery":"","loftocean_post_format_gallery_ids":"","loftocean_post_format_gallery_urls":"","loftocean_post_format_video_id":0,"loftocean_post_format_video_url":"","loftocean_post_format_video_type":"","loftocean_post_format_video":"","loftocean_post_format_audio_type":"","loftocean_post_format_audio_url":"","loftocean_post_format_audio_id":0,"loftocean_post_format_audio":"","loftocean-featured-post":"","loftocean-like-count":0,"loftocean-view-count":1232,"loftocean_coauthors":"","alpaca_post_content_reading_setting":"","alpaca_reading_speed_per_minute":0,"alpaca_reading_speed_unit":"","alpaca_single_post_template_layout":"","footnotes":""},"categories":[1],"tags":[1037,1603,1958,2069],"class_list":["post-484","post","type-post","status-publish","format-standard","hentry","category-uncategorized","tag-i-get-seasonal-affective-disorder-in-the-summer","tag-personal","tag-summer-in-amsterdam","tag-this-is-now-a-cat-lady-blog"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>- The Research Papers<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/theresearchpapers.org\/archive\/the-world-outside-right-now-meanwhile\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"- The Research Papers\" \/>\n<meta property=\"og:description\" content=\"The world outside right now: Meanwhile, overlord Number 1 (who is actually &ldquo;overlady&rdquo;): And overlord Number 2:\" \/>\n<meta property=\"og:url\" content=\"https:\/\/theresearchpapers.org\/archive\/the-world-outside-right-now-meanwhile\/\" \/>\n<meta property=\"og:site_name\" content=\"The Research Papers\" \/>\n<meta property=\"article:published_time\" content=\"2012-08-06T11:45:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/theresearchpapers.org\/archive\/wp-content\/uploads\/2021\/08\/40c3e7bda371eecea1f6acd0487c93a62e40f648.jpg\" \/>\n<meta name=\"author\" content=\"Flavia Dzodan\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Flavia Dzodan\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/theresearchpapers.org\/archive\/the-world-outside-right-now-meanwhile\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/theresearchpapers.org\/archive\/the-world-outside-right-now-meanwhile\/\"},\"author\":{\"name\":\"Flavia Dzodan\",\"@id\":\"https:\/\/theresearchpapers.org\/archive\/#\/schema\/person\/69281d20ffc4c45de29cedfa61ec6e38\"},\"headline\":\"No title\",\"datePublished\":\"2012-08-06T11:45:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/theresearchpapers.org\/archive\/the-world-outside-right-now-meanwhile\/\"},\"wordCount\":17,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/theresearchpapers.org\/archive\/#organization\"},\"image\":{\"@id\":\"https:\/\/theresearchpapers.org\/archive\/the-world-outside-right-now-meanwhile\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/theresearchpapers.org\/archive\/wp-content\/uploads\/2021\/08\/40c3e7bda371eecea1f6acd0487c93a62e40f648.jpg\",\"keywords\":[\"I get seasonal affective disorder in the summer\",\"personal\",\"summer in Amsterdam\",\"this is now a cat lady blog\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/theresearchpapers.org\/archive\/the-world-outside-right-now-meanwhile\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/theresearchpapers.org\/archive\/the-world-outside-right-now-meanwhile\/\",\"url\":\"https:\/\/theresearchpapers.org\/archive\/the-world-outside-right-now-meanwhile\/\",\"name\":\"- The Research Papers\",\"isPartOf\":{\"@id\":\"https:\/\/theresearchpapers.org\/archive\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/theresearchpapers.org\/archive\/the-world-outside-right-now-meanwhile\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/theresearchpapers.org\/archive\/the-world-outside-right-now-meanwhile\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/theresearchpapers.org\/archive\/wp-content\/uploads\/2021\/08\/40c3e7bda371eecea1f6acd0487c93a62e40f648.jpg\",\"datePublished\":\"2012-08-06T11:45:59+00:00\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/theresearchpapers.org\/archive\/the-world-outside-right-now-meanwhile\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/theresearchpapers.org\/archive\/the-world-outside-right-now-meanwhile\/#primaryimage\",\"url\":\"https:\/\/theresearchpapers.org\/archive\/wp-content\/uploads\/2021\/08\/40c3e7bda371eecea1f6acd0487c93a62e40f648.jpg\",\"contentUrl\":\"https:\/\/theresearchpapers.org\/archive\/wp-content\/uploads\/2021\/08\/40c3e7bda371eecea1f6acd0487c93a62e40f648.jpg\",\"width\":500,\"height\":667},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/theresearchpapers.org\/archive\/#website\",\"url\":\"https:\/\/theresearchpapers.org\/archive\/\",\"name\":\"The Research Papers\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/theresearchpapers.org\/archive\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/theresearchpapers.org\/archive\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/theresearchpapers.org\/archive\/#organization\",\"name\":\"The Research Papers\",\"url\":\"https:\/\/theresearchpapers.org\/archive\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/theresearchpapers.org\/archive\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/theresearchpapers.org\/archive\/wp-content\/uploads\/2021\/07\/cropped-Screenshot-2021-07-29-at-15.01.52.png\",\"contentUrl\":\"https:\/\/theresearchpapers.org\/archive\/wp-content\/uploads\/2021\/07\/cropped-Screenshot-2021-07-29-at-15.01.52.png\",\"width\":943,\"height\":269,\"caption\":\"The Research Papers\"},\"image\":{\"@id\":\"https:\/\/theresearchpapers.org\/archive\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/theresearchpapers.org\/archive\/#\/schema\/person\/69281d20ffc4c45de29cedfa61ec6e38\",\"name\":\"Flavia Dzodan\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/theresearchpapers.org\/archive\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a3eedf3ed7334274cfc4d525a46aa4e85c5a246418835528410ecf354d0861e1?s=96&d=monsterid&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a3eedf3ed7334274cfc4d525a46aa4e85c5a246418835528410ecf354d0861e1?s=96&d=monsterid&r=g\",\"caption\":\"Flavia Dzodan\"},\"url\":\"https:\/\/theresearchpapers.org\/archive\/author\/trp-adm-fdz02\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"- The Research Papers","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/theresearchpapers.org\/archive\/the-world-outside-right-now-meanwhile\/","og_locale":"en_US","og_type":"article","og_title":"- The Research Papers","og_description":"The world outside right now: Meanwhile, overlord Number 1 (who is actually &ldquo;overlady&rdquo;): And overlord Number 2:","og_url":"https:\/\/theresearchpapers.org\/archive\/the-world-outside-right-now-meanwhile\/","og_site_name":"The Research Papers","article_published_time":"2012-08-06T11:45:59+00:00","og_image":[{"url":"https:\/\/theresearchpapers.org\/archive\/wp-content\/uploads\/2021\/08\/40c3e7bda371eecea1f6acd0487c93a62e40f648.jpg","type":"","width":"","height":""}],"author":"Flavia Dzodan","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Flavia Dzodan"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/theresearchpapers.org\/archive\/the-world-outside-right-now-meanwhile\/#article","isPartOf":{"@id":"https:\/\/theresearchpapers.org\/archive\/the-world-outside-right-now-meanwhile\/"},"author":{"name":"Flavia Dzodan","@id":"https:\/\/theresearchpapers.org\/archive\/#\/schema\/person\/69281d20ffc4c45de29cedfa61ec6e38"},"headline":"No title","datePublished":"2012-08-06T11:45:59+00:00","mainEntityOfPage":{"@id":"https:\/\/theresearchpapers.org\/archive\/the-world-outside-right-now-meanwhile\/"},"wordCount":17,"commentCount":0,"publisher":{"@id":"https:\/\/theresearchpapers.org\/archive\/#organization"},"image":{"@id":"https:\/\/theresearchpapers.org\/archive\/the-world-outside-right-now-meanwhile\/#primaryimage"},"thumbnailUrl":"https:\/\/theresearchpapers.org\/archive\/wp-content\/uploads\/2021\/08\/40c3e7bda371eecea1f6acd0487c93a62e40f648.jpg","keywords":["I get seasonal affective disorder in the summer","personal","summer in Amsterdam","this is now a cat lady blog"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/theresearchpapers.org\/archive\/the-world-outside-right-now-meanwhile\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/theresearchpapers.org\/archive\/the-world-outside-right-now-meanwhile\/","url":"https:\/\/theresearchpapers.org\/archive\/the-world-outside-right-now-meanwhile\/","name":"- The Research Papers","isPartOf":{"@id":"https:\/\/theresearchpapers.org\/archive\/#website"},"primaryImageOfPage":{"@id":"https:\/\/theresearchpapers.org\/archive\/the-world-outside-right-now-meanwhile\/#primaryimage"},"image":{"@id":"https:\/\/theresearchpapers.org\/archive\/the-world-outside-right-now-meanwhile\/#primaryimage"},"thumbnailUrl":"https:\/\/theresearchpapers.org\/archive\/wp-content\/uploads\/2021\/08\/40c3e7bda371eecea1f6acd0487c93a62e40f648.jpg","datePublished":"2012-08-06T11:45:59+00:00","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/theresearchpapers.org\/archive\/the-world-outside-right-now-meanwhile\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/theresearchpapers.org\/archive\/the-world-outside-right-now-meanwhile\/#primaryimage","url":"https:\/\/theresearchpapers.org\/archive\/wp-content\/uploads\/2021\/08\/40c3e7bda371eecea1f6acd0487c93a62e40f648.jpg","contentUrl":"https:\/\/theresearchpapers.org\/archive\/wp-content\/uploads\/2021\/08\/40c3e7bda371eecea1f6acd0487c93a62e40f648.jpg","width":500,"height":667},{"@type":"WebSite","@id":"https:\/\/theresearchpapers.org\/archive\/#website","url":"https:\/\/theresearchpapers.org\/archive\/","name":"The Research Papers","description":"","publisher":{"@id":"https:\/\/theresearchpapers.org\/archive\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/theresearchpapers.org\/archive\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/theresearchpapers.org\/archive\/#organization","name":"The Research Papers","url":"https:\/\/theresearchpapers.org\/archive\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/theresearchpapers.org\/archive\/#\/schema\/logo\/image\/","url":"https:\/\/theresearchpapers.org\/archive\/wp-content\/uploads\/2021\/07\/cropped-Screenshot-2021-07-29-at-15.01.52.png","contentUrl":"https:\/\/theresearchpapers.org\/archive\/wp-content\/uploads\/2021\/07\/cropped-Screenshot-2021-07-29-at-15.01.52.png","width":943,"height":269,"caption":"The Research Papers"},"image":{"@id":"https:\/\/theresearchpapers.org\/archive\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/theresearchpapers.org\/archive\/#\/schema\/person\/69281d20ffc4c45de29cedfa61ec6e38","name":"Flavia Dzodan","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/theresearchpapers.org\/archive\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a3eedf3ed7334274cfc4d525a46aa4e85c5a246418835528410ecf354d0861e1?s=96&d=monsterid&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a3eedf3ed7334274cfc4d525a46aa4e85c5a246418835528410ecf354d0861e1?s=96&d=monsterid&r=g","caption":"Flavia Dzodan"},"url":"https:\/\/theresearchpapers.org\/archive\/author\/trp-adm-fdz02\/"}]}},"loftoceanMetas":{"readingTime":"&lt; 1 min read","authorName":"Flavia Dzodan","categories":[{"name":"Uncategorized","link":"https:\/\/theresearchpapers.org\/archive\/category\/uncategorized\/","count":3467}],"date":"06.08.2012"},"_links":{"self":[{"href":"https:\/\/theresearchpapers.org\/archive\/wp-json\/wp\/v2\/posts\/484","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/theresearchpapers.org\/archive\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/theresearchpapers.org\/archive\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/theresearchpapers.org\/archive\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/theresearchpapers.org\/archive\/wp-json\/wp\/v2\/comments?post=484"}],"version-history":[{"count":0,"href":"https:\/\/theresearchpapers.org\/archive\/wp-json\/wp\/v2\/posts\/484\/revisions"}],"wp:attachment":[{"href":"https:\/\/theresearchpapers.org\/archive\/wp-json\/wp\/v2\/media?parent=484"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/theresearchpapers.org\/archive\/wp-json\/wp\/v2\/categories?post=484"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/theresearchpapers.org\/archive\/wp-json\/wp\/v2\/tags?post=484"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}